{"id":30679,"date":"2023-11-10T16:56:12","date_gmt":"2023-11-10T15:56:12","guid":{"rendered":"https:\/\/car4rent.fr\/location-de-voitures-de-prestige\/"},"modified":"2024-02-16T13:57:26","modified_gmt":"2024-02-16T12:57:26","slug":"location-de-voitures-de-prestige","status":"publish","type":"page","link":"https:\/\/car4rent.fr\/fr\/location-de-voitures-de-prestige\/","title":{"rendered":"Location de voitures de prestige"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-be0xv36-92215862df651123f67c2a87514dd08b\">\n.avia-section.av-be0xv36-92215862df651123f67c2a87514dd08b .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/car4rent.fr\/wp-content\/uploads\/radisson-terrasse-nuit.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-be0xv36-92215862df651123f67c2a87514dd08b main_color avia-section-huge avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch av-parallax-section avia-bg-style-parallax av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><a href='#next-section' title='' class='scroll-down-link  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='down-open-mini' data-av_iconset='svg_entypo-fontello'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Scroller vers la prochaine section<\/title>\n<desc id='av-svg-desc-1'>Scroller vers la prochaine section<\/desc>\n<path d=\"M12.96 12.16q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-6.272 6.144q-0.704 0.704-1.536 0l-6.272-6.144q-0.832-0.832 0-1.536 0.768-0.768 1.6 0l5.44 4.992z\"><\/path>\n<\/svg><\/a><div class='container av-section-cont-open' ><main  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30679'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av8rvcy-e8d33525ee0b6404017dce0b1f92bb33\">\n.flex_column.av-av8rvcy-e8d33525ee0b6404017dce0b1f92bb33{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\nbackground-color:rgba(0,0,0,0.47);\n}\n<\/style>\n<div  class='flex_column av-av8rvcy-e8d33525ee0b6404017dce0b1f92bb33 av_two_third  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-a9triyq-be014a63e3f3e228861b29c4ad488d2b\">\n#top .av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b{\npadding-bottom:10px;\ncolor:#ffffff;\nfont-size:35px;\n}\nbody .av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-a9triyq-be014a63e3f3e228861b29c4ad488d2b .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-a9triyq-be014a63e3f3e228861b29c4ad488d2b av-special-heading-h3 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-2  avia-builder-el-no-sibling  av-inherit-size'><h3 class='av-special-heading-tag '  >Location de voitures de prestige &#8211; Passer \u00e0 la dimension du luxe<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div><\/div><\/div><\/main><!-- close content main element --><\/div><\/div><\/div><div id='av_section_2'  class='avia-section av-a0ktxhe-2f37cf9fb19fa7b2fc009620b958c87d main_color avia-section-default avia-no-shadow  avia-builder-el-3  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30679'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241\">\n#top .av-special-heading.av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241{\npadding-bottom:10px;\nfont-size:35px;\n}\nbody .av-special-heading.av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241 .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-9bfzcaq-08cd4404915499f0fc8089d1a1d03241 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-4  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h1 class='av-special-heading-tag '  >Location de voitures de prestige &#8211; D\u00e9couvrez la location de v\u00e9hicules haut de gamme &#8211; Passez \u00e0 la dimension du luxe avec Car4rent<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  class='hr av-8v6lybm-982f79fd293939c8ff9bb99c350884e7 hr-default  avia-builder-el-5  el_after_av_heading  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-8kz32le-cb6219b04acf317808e9a2b846646857 '  ><div class='avia_textblock' ><section id=\"block0\" class=\"stripe row-content block0 fullwidth\">\n<div class=\"column small-five small-push-one reset last\">\n<div class=\"boxcontent\">\n<h2><strong>Location de voitures de prestige &#8211; Passer \u00e0 la dimension du luxe<\/strong><\/h2>\n<p>Faites l&rsquo;exp\u00e9rience de la location de voitures de prestige et passez \u00e0 la dimension du luxe avec Car4rent &#8211; Location de voitures de prestige C\u00f4te d&rsquo;Azur, location de voitures de luxe, de voitures de fonction, de voitures de sport, de cabriolets et de supercars. Avec une flotte estim\u00e9e de voitures de luxe de mod\u00e8les aussi prestigieux les uns que les autres tels que Ferrari, Lamborghini, Porsche, Land Rover, Mercedes AMG, Bentley, Rolls-Royce et plus encore, nous sommes d\u00e9di\u00e9s \u00e0 te fournir une exp\u00e9rience de location d&rsquo;\u00e9lite entre Monaco et Saint-Tropez<strong>.<\/strong><\/p>\n<p>Visite Cannes, l&rsquo;une des villes les plus exclusives de la C\u00f4te d&rsquo;Azur et la location d&rsquo;une voiture de luxe \u00e0 Cannes te permet de profiter des paillettes et du glamour de la C\u00f4te d&rsquo;Azur dans un style magnifique. Profite de l&rsquo;extravagance de la Rolls-Royce Dawn pour ton mariage de luxe sur la C\u00f4te d&rsquo;Azur, ou fais une entr\u00e9e remarqu\u00e9e au Festival de Cannes annuel dans une Bentley Continental GTC.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-26422\" src=\"https:\/\/car4rent.fr\/wp-content\/uploads\/BENTLEY-HIRE.jpg\" alt=\"Location de voitures de prestige, location de BENTLEY, louer une voiture de luxe \u00e0 Cannes\" width=\"400\" height=\"300\" title=\"Car4Rent Cannes\" srcset=\"https:\/\/car4rent.fr\/wp-content\/uploads\/BENTLEY-HIRE.jpg 320w, https:\/\/car4rent.fr\/wp-content\/uploads\/BENTLEY-HIRE-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><img decoding=\"async\" class=\"alignnone wp-image-37214 \" src=\"https:\/\/car4rent.fr\/wp-content\/uploads\/nsmail.jpg\" alt=\"Location de voitures de prestige, Louer une voiture de luxe, R\u00e9server une voiture de sport de luxe \u00e0 Monaco maintenant\" width=\"271\" height=\"300\" title=\"Car4Rent Cannes\" srcset=\"https:\/\/car4rent.fr\/wp-content\/uploads\/\/nsmail.jpg 463w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/nsmail-271x300.jpg 271w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/nsmail-450x498.jpg 450w\" sizes=\"(max-width: 271px) 100vw, 271px\" \/><\/p>\n<p>Profitez d&rsquo;une exp\u00e9rience de conduite \u00e0 bord de v\u00e9hicules de luxe tels que Rolls-Royce ou Bentley pour les plus c\u00e9l\u00e8bres, mais essayez aussi d&rsquo;autres marques et mod\u00e8les. Les voitures de luxe se pr\u00e9sentent sous toutes les formes et tailles, avec des SUV haut de gamme de Bentley, Range Rover et Porsche, des supercars \u00e0 hautes performances de Lamborghini, Ferrari ou AMG et des voitures de prestige de Mercedes et Jaguar.<\/p>\n<p>D\u00e9couvre les points forts de Cannes, y compris une visite au typique March\u00e9 Forville (march\u00e9 alimentaire) de la rue Meynadier et les boutiques de cr\u00e9ateurs de La Croisette avant de faire une promenade en plein air dans ta Lamborghini Huracan Spyder le long de la c\u00f4te m\u00e9diterran\u00e9enne jusqu&rsquo;aux stations baln\u00e9aires d&rsquo;Antibes, Juan-Les-Pins et Saint-Tropez. Arrive avec style \u00e0 l&rsquo;h\u00f4tel Majestic Barri\u00e8re de Cannes dans une Rolls-Royce Drophead, fleuron du constructeur britannique, ou gare-toi \u00e0 l&rsquo;h\u00f4tel Intercontinental Carlton de Cannes dans une impressionnante Mercedes G-Class 500 4&#215;4\u00b2.<\/p>\n<h2>Location de voitures de prestige<\/h2>\n<p>Car4rent fournit un service in\u00e9gal\u00e9 aux secteurs des loisirs et des affaires en combinant des prix extr\u00eamement comp\u00e9titifs et un excellent service \u00e0 la client\u00e8le. Nous sommes tellement convaincus que nous ne pouvons pas \u00eatre \u00e9gal\u00e9s en termes de prix que si vous trouvez un devis moins cher pour l&rsquo;une de nos voitures aupr\u00e8s des principaux concurrents locaux, nous nous alignerons sur celui-ci. \u00c0 condition que nous puissions le v\u00e9rifier.<\/p>\n<h3><strong>Location de voiture de prestige &#8211; Prise en charge \u00e0 l&rsquo;endroit de ton choix.<\/strong><\/h3>\n<p>La plupart des visiteurs de Cannes arriveront \u00e0 l&rsquo;a\u00e9roport international C\u00f4te d&rsquo;Azur de Nice, mais tu peux aussi r\u00e9cup\u00e9rer ta location de voiture de luxe \u00e0 l&rsquo;a\u00e9roport Cannes Mandelieu, pr\u00e8s de notre parking. Ta voiture peut aussi \u00eatre livr\u00e9e \u00e0 l&rsquo;endroit de ton choix partout en France et dans le nord de l&rsquo;Italie.<\/p>\n<h4><strong>Location de voitures de prestige &#8211; Service client\u00e8le de premier ordre<\/strong><\/h4>\n<p>R\u00e9server une location de voiture C\u00f4te d&rsquo;Azur avec notre \u00e9quipe de service \u00e0 la client\u00e8le est tr\u00e8s facile. Notre personnel attentif se met en quatre pour faire de votre exp\u00e9rience de conduite une exp\u00e9rience sensationnelle et sera \u00e0 votre disposition pour veiller \u00e0 ce que chaque d\u00e9tail soit r\u00e9gl\u00e9 pour faire de votre voyage un moment inoubliable. Notre service ne s&rsquo;arr\u00eate pas \u00e0 la livraison du v\u00e9hicule. Si tu rencontres un probl\u00e8me pendant ton s\u00e9jour, n&rsquo;h\u00e9site pas \u00e0 joindre l&rsquo;un des membres de notre personnel pour t&rsquo;aider imm\u00e9diatement.<\/p>\n<p>N&rsquo;h\u00e9sitez pas \u00e0 <a href=\"https:\/\/car4rent.fr\/fr\/contact\/\" target=\"_blank\" rel=\"noopener\"><strong>contacter<\/strong> <\/a>notre \u00e9quipe pour toute information compl\u00e9mentaire<\/p>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"block1\" class=\"stripe row-content block1 fullwidth\">\n<\/section>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-86tv0w2-372187701b8a422dd22f919ddaf80c29\">\n.flex_column.av-86tv0w2-372187701b8a422dd22f919ddaf80c29{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-86tv0w2-372187701b8a422dd22f919ddaf80c29 av_one_third  avia-builder-el-7  el_after_av_textblock  el_before_av_one_third  first flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7i9m18i-6e534bd84ae82144cdf898cceec0f679\">\n.iconbox.av-7i9m18i-6e534bd84ae82144cdf898cceec0f679 .iconbox_icon{\nbackground-color:#6834bd;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-7i9m18i-6e534bd84ae82144cdf898cceec0f679  avia-builder-el-8  avia-builder-el-no-sibling  main_color' ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue82a' data-av_iconfont='entypo-fontello'  ><\/div><\/header><div class='iconbox_content_container ' ><p><span style=\"font-size: 14pt;\">Location de voiture de luxe C\u00f4te d&rsquo;Azur<\/span><\/p>\n<hr>\n<p>Nous proposons une large gamme de SUV, cabriolets, voitures de sport et de luxe \u00e0 louer. Notre service, adapt\u00e9 sp\u00e9cifiquement \u00e0 tes besoins ou \u00e0 ceux de tes clients, ne s&rsquo;arr\u00eate pas \u00e0 la fourniture de v\u00e9hicules de luxe.<\/p>\n<p>Prise en charge et d\u00e9pose \u00e0 l&rsquo;a\u00e9roport de Nice ou \u00e0 tout autre endroit hors a\u00e9roport.<\/p>\n<p>Prix abordables : journ\u00e9e \u00e0 partir de 260\u20ac<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-77ruhwi-ebd3e63e18413f3c39f1521ef39365c2\">\n.flex_column.av-77ruhwi-ebd3e63e18413f3c39f1521ef39365c2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-77ruhwi-ebd3e63e18413f3c39f1521ef39365c2 av_one_third  avia-builder-el-9  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6j05l6q-86ea5149001d3503f9978e03b686e216\">\n.iconbox.av-6j05l6q-86ea5149001d3503f9978e03b686e216 .iconbox_icon{\nbackground-color:#6834bd;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-6j05l6q-86ea5149001d3503f9978e03b686e216  avia-builder-el-10  avia-builder-el-no-sibling  main_color' ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue842' data-av_iconfont='entypo-fontello'  ><\/div><\/header><div class='iconbox_content_container ' ><p><span style=\"font-size: 14pt;\">A\u00e9roport de Cannes, St-Tropez, Monaco et Nice<\/span><\/p>\n<hr>\n<p>Utilisez notre service une fois et vous ne ferez plus jamais appel \u00e0 une autre soci\u00e9t\u00e9. Nous fournissons un service amical, de sorte que les clients se sentent d\u00e9tendus en prenant nos v\u00e9hicules, car chaque r\u00e9servation est adapt\u00e9e \u00e0 leurs besoins.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6728h9e-dcd1e883c82424f8d1c94be4e2b3a9d5\">\n.flex_column.av-6728h9e-dcd1e883c82424f8d1c94be4e2b3a9d5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-6728h9e-dcd1e883c82424f8d1c94be4e2b3a9d5 av_one_third  avia-builder-el-11  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5qj7vaa-3e441c127852004f831a5f47ec25c176\">\n.iconbox.av-5qj7vaa-3e441c127852004f831a5f47ec25c176 .iconbox_icon{\nbackground-color:#6834bd;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-5qj7vaa-3e441c127852004f831a5f47ec25c176  avia-builder-el-12  avia-builder-el-no-sibling  main_color' ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue80b' data-av_iconfont='entypo-fontello'  ><\/div><\/header><div class='iconbox_content_container ' ><p><span style=\"font-size: 14pt;\">Un service sur mesure<\/span><\/p>\n<hr>\n<p>Une \u00e9quipe d\u00e9vou\u00e9e et attentive est \u00e0 ta disposition pour te fournir toute information ou r\u00e9pondre \u00e0 tes demandes. Ta voiture peut \u00eatre livr\u00e9e sur demande directement \u00e0 ton arriv\u00e9e \u00e0 l&rsquo;a\u00e9roport de Nice, \u00e0 l&rsquo;a\u00e9roport de Gen\u00e8ve, \u00e0 l&rsquo;a\u00e9roport de Lyon Saint-Exup\u00e9ry. ou vers ton lieu de vacances, \u00e0 ton h\u00f4tel ou n&rsquo;importe o\u00f9 en France vers la destination de ton choix.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='contactez-nous'  class='avia-section av-5803nya-7811a140526f56dea39680ee99a70145 main_color avia-section-default avia-no-border-styling  avia-builder-el-13  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30679'><div class='entry-content-wrapper clearfix'>\n<div  class='hr av-51rpe1u-8f79b67eb25868dd685a8f896c576dfa hr-default  avia-builder-el-14  el_before_av_heading  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4a8risi-ad18fda02bbd9702fe7b33bfb27d907b\">\n#top .av-special-heading.av-4a8risi-ad18fda02bbd9702fe7b33bfb27d907b{\npadding-bottom:25px;\n}\nbody .av-special-heading.av-4a8risi-ad18fda02bbd9702fe7b33bfb27d907b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-4a8risi-ad18fda02bbd9702fe7b33bfb27d907b .av-subheading{\nfont-size:20px;\n}\n<\/style>\n<div  class='av-special-heading av-4a8risi-ad18fda02bbd9702fe7b33bfb27d907b av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-15  el_after_av_hr  el_before_av_hr '><h3 class='av-special-heading-tag '  >Vous souhaitez louer une voiture de luxe sur la C\u00f4te d\u2019Azur ? Besoin d\u2019un conseil ?<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3vicfya-c81e5a52a43a1eb8a618957977ccbc41\">\n#top .hr.hr-invisible.av-3vicfya-c81e5a52a43a1eb8a618957977ccbc41{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-3vicfya-c81e5a52a43a1eb8a618957977ccbc41 hr-invisible  avia-builder-el-16  el_after_av_heading  el_before_av_two_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3m08rr6-78efa2c27cea160528607d0083330da2\">\n.flex_column.av-3m08rr6-78efa2c27cea160528607d0083330da2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3m08rr6-78efa2c27cea160528607d0083330da2 av_two_third  avia-builder-el-17  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><p><section  class='av_textblock_section av-3zo5lu-31a23a5aeefe2db4775a00d6a5555428 '  ><div class='avia_textblock' ><p><span style=\"font-size: 14pt;\">Contactez-nous \u00e0 l&rsquo;aide du formulaire ci-dessous<\/span><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-2q2xlky-a85aade8d46fc89bc8d8da780cb2d5df '  ><div class='avia_textblock' ><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-27233\"><form id=\"wpforms-form-27233\" class=\"wpforms-validate wpforms-form\" data-formid=\"27233\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/30679\" data-token=\"ea956caa849f38ed111b97e9a0a1fee9\" data-token-time=\"1784092303\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27233-field_5-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"5\"><label class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-27233-field_5\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][5][first]\" required><label for=\"wpforms-27233-field_5\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-27233-field_5-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][5][last]\" required><label for=\"wpforms-27233-field_5-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-27233-field_9-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"9\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-27233-field_7-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-27233-field_7\">Courriel <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-27233-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" spellcheck=\"false\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-27233-field_8-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-27233-field_8\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-27233-field_8\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][8]\" aria-label=\"T\u00e9l\u00e9phone\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-27233-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27233-field_4\">Message<\/label><textarea id=\"wpforms-27233-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27233\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages\/30679\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27233\" class=\"wpforms-submit\" data-alt-text=\"Envoi\" data-submit-text=\"Soumettre\" aria-live=\"assertive\" value=\"wpforms-submit\">Soumettre<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-258xuua-555f4a04c6feffe71cf42a6d11f50359\">\n.flex_column.av-258xuua-555f4a04c6feffe71cf42a6d11f50359{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-258xuua-555f4a04c6feffe71cf42a6d11f50359 av_one_third  avia-builder-el-20  el_after_av_two_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><p><section  class='av_textblock_section av-1bpu92a-a7c17dd418f0080dd881250e39d88eb4 '  ><div class='avia_textblock' ><p><span style=\"font-size: 14pt;\">Nous contacter par t\u00e9l\u00e9phone<\/span><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-w3khcy-fd24b5120d01c6b716be1075905463fa '  ><div class='avia_textblock' ><p>Bureau de Cannes (09H-12H00 et 15H00-19H00)<br \/>\n10, rue Hibert, 06400 Cannes<br \/>\nT\u00e9l\u00e9phone : <a href=\"tel:0033788278586\">0033 7 88 27 85 86<\/a><br \/>\nMail : <a href=\"mailto:info@car4rent.fr\">info@car4rent.fr<\/a><\/p>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-dtiki-aedcb514f52ca64b83b1b8dc044005a8 main_color avia-section-default avia-no-border-styling  avia-builder-el-23  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30679'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-builder-widget-area clearfix  avia-builder-el-24  avia-builder-el-no-sibling '><div id=\"text-9\" class=\"widget clearfix widget_text\">\t\t\t<div class=\"textwidget\"><p style=\"text-align: center;\">    <div class=\"car4rent-share-block car4rent-fr\">\n        <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-facebook\"><\/i> Partager<\/a>\n        <a href=\"https:\/\/x.com\/intent\/tweet?url=&amp;text=\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-x-twitter\"><\/i> X<\/a>\n        <a href=\"https:\/\/wa.me\/?text=%20\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-whatsapp\"><\/i> WhatsApp<\/a>\n        <a href=\"https:\/\/www.instagram.com\/car4rent_cannes\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-instagram\"><\/i> Instagram<\/a>\n        <a href=\"https:\/\/www.linkedin.com\/company\/car4rent\/about\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-linkedin\"><\/i> LinkedIn<\/a>\n        <a href=\"https:\/\/www.youtube.com\/@car4rentcannes839\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-youtube\"><\/i> YouTube<\/a>\n    <\/div>\n    <\/p>\n<\/div>\n\t\t<\/div><\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":30024,"parent":0,"menu_order":635,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30679","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages\/30679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/comments?post=30679"}],"version-history":[{"count":0,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages\/30679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/media\/30024"}],"wp:attachment":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/media?parent=30679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}