{"id":30641,"date":"2023-11-10T16:56:12","date_gmt":"2023-11-10T15:56:12","guid":{"rendered":"https:\/\/car4rent.fr\/location-de-voitures-exotiques-2\/"},"modified":"2024-03-11T21:02:25","modified_gmt":"2024-03-11T20:02:25","slug":"location-de-voiture-exotique","status":"publish","type":"page","link":"https:\/\/car4rent.fr\/fr\/location-de-voiture-exotique\/","title":{"rendered":"Location de voiture exotique"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-b4wlb06-3c667772b1f7b77876a71bc896810f6f\">\n.avia-section.av-b4wlb06-3c667772b1f7b77876a71bc896810f6f .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/car4rent.fr\/wp-content\/uploads\/vieux-port-2.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-b4wlb06-3c667772b1f7b77876a71bc896810f6f main_color avia-section-huge avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch av-parallax-section avia-bg-style-parallax av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><a href='#next-section' title='' class='scroll-down-link  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='down-open-mini' data-av_iconset='svg_entypo-fontello'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Scroller vers la prochaine section<\/title>\n<desc id='av-svg-desc-1'>Scroller vers la prochaine section<\/desc>\n<path d=\"M12.96 12.16q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-6.272 6.144q-0.704 0.704-1.536 0l-6.272-6.144q-0.832-0.832 0-1.536 0.768-0.768 1.6 0l5.44 4.992z\"><\/path>\n<\/svg><\/a><div class='container av-section-cont-open' ><main  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30641'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-aqaxp06-a4b5219faf6802da54664fb28fe987e2\">\n.flex_column.av-aqaxp06-a4b5219faf6802da54664fb28fe987e2{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\nbackground-color:rgba(0,0,0,0.47);\n}\n<\/style>\n<div  class='flex_column av-aqaxp06-a4b5219faf6802da54664fb28fe987e2 av_two_third  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b\">\n#top .av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b{\npadding-bottom:10px;\ncolor:#ffffff;\nfont-size:35px;\n}\nbody .av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-ael1xqu-3d5f57003e97d6a9c4c1fefb101f527b av-special-heading-h4 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-2  avia-builder-el-no-sibling  av-inherit-size'><h4 class='av-special-heading-tag '  >Location de voiture exotique<\/h4><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><\/div><div id='av_section_2'  class='avia-section av-9rdsx6e-9282fd6d4bc7c09960c909530cdd1fb7 main_color avia-section-default avia-no-shadow  avia-builder-el-3  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30641'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-s66186-3f6c7e508df222abbf112f2cd60a7027\">\n#top .av-special-heading.av-s66186-3f6c7e508df222abbf112f2cd60a7027{\npadding-bottom:10px;\nfont-size:35px;\n}\nbody .av-special-heading.av-s66186-3f6c7e508df222abbf112f2cd60a7027 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-s66186-3f6c7e508df222abbf112f2cd60a7027 .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-s66186-3f6c7e508df222abbf112f2cd60a7027 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-s66186-3f6c7e508df222abbf112f2cd60a7027 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-s66186-3f6c7e508df222abbf112f2cd60a7027 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-s66186-3f6c7e508df222abbf112f2cd60a7027 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-4  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h2 class='av-special-heading-tag '  >Location de voiture exotique au meilleur prix<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  class='hr av-94j6amu-f8126d7c133b7247fcff6905be19fdb6 hr-default  avia-builder-el-5  el_after_av_heading  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<section  class='av_textblock_section av-8n5fpue-034351aef3169449ca40fe86248740f8 '  ><div class='avia_textblock' ><section id=\"block0\" class=\"stripe row-content block0 fullwidth\">\n<div class=\"column small-five small-push-one reset last\">\n<div class=\"boxcontent\">\n<h2><strong>Location de voiture Exotique : conduisez la voiture de vos r\u00eaves avec style<\/strong><\/h2>\n<p>Bienvenue dans le monde de la location de voiture exotique et de luxe. Car4rent est l&rsquo;un des principaux loueurs de voitures haut de gamme et de voitures de sport sur la <a href=\"https:\/\/generationvoyage.fr\/visiter-cote-azur-faire-voir\/\" target=\"_blank\" rel=\"noopener\">C\u00f4te d&rsquo;Azur<\/a> et poss\u00e8de des agences \u00e0 <a href=\"https:\/\/www.cannes-destination.fr\/visites-incontournables\" target=\"_blank\" rel=\"noopener\">Cannes<\/a>, <a href=\"http:\/\/www.visitmonaco.com\/\" target=\"_blank\" rel=\"noopener\">Monaco<\/a>, <a href=\"https:\/\/www.sainttropeztourisme.com\/\" target=\"_blank\" rel=\"noopener\">Saint-Tropez<\/a> et \u00e0 l&rsquo;a\u00e9roport de Nice.<\/p>\n<p>La location de voiture exotique \u00e0 Cannes vous permettra de faire une forte impression. Nous proposons un large choix de mod\u00e8les aussi prestigieux les uns que les autres tels que<a href=\"https:\/\/car4rent.fr\/fr\/louer-une-ferrari\/\"><strong>Ferrari<\/strong><\/a>,\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-une-lamborghini\/\"><strong>Lamborghini<\/strong><\/a>,\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-une-porsche\/\"><strong>Porsche<\/strong><\/a>,\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-un-land-rover\/\"><strong>Land Rover<\/strong><\/a>,\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-une-mercedes\/\"><strong>Mercedes AMG<\/strong><\/a>,\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-une-bentley\/\"><strong>Bentley<\/strong><\/a>,\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-une-rolls-royce\/\"><strong>Rolls-Royce<\/strong><\/a>, et\n            <a href=\"https:\/\/car4rent.fr\/fr\/louer-une-audi\/\"><strong>Audi<\/strong><\/a>.\u00a0 Bienvenue dans le monde du luxe.<\/p>\n<p>Louez une voiture exotique et profitez de la vie \u00e0 Cannes et de ses \u00e9v\u00e9nements c\u00e9l\u00e8bres tels que <strong>Festival de Cannes<\/strong> et le Cannes Lions, le festival de la cr\u00e9ativit\u00e9 o\u00f9 nous avons la chance de voir nos stars de cin\u00e9ma pr\u00e9f\u00e9r\u00e9es et d&rsquo;autres personnes influentes fouler le tapis rouge dans les derni\u00e8res cr\u00e9ations de haute couture, ann\u00e9e apr\u00e8s ann\u00e9e.<\/p>\n<p>Cannes est la ville du luxe sans compromis, qui nous invite \u00e0 profiter de ses nombreux h\u00f4tels, de ses restaurants gastronomiques et de son style de vie glamour. Et \u00e9tant donn\u00e9 que Cannes entretient une longue tradition de services touristiques de premier ordre et qu&rsquo;elle est un endroit o\u00f9 il fait bon vivre, il est tout \u00e0 fait compr\u00e9hensible que l&rsquo;on ait choisi de s&rsquo;y installer.<\/p>\n<p>Mais ce n&rsquo;est pas tout. Il semble que l&rsquo;\u00e9conomie et l&rsquo;industrie progressent \u00e9galement ici, car c&rsquo;est le si\u00e8ge principal de centaines d&rsquo;entreprises prosp\u00e8res, dont beaucoup sont actives dans le commerce et la prestation de services.<\/p>\n<h5>Location Lamborghini Huracan Spyder<\/h5>\n<p>Vous souhaitez vous faire plaisir. Offrez-vous une exp\u00e9rience de conduite ltime en louant une Lamborghini Huracan Spyder. Une puissance inouie permettant une conduite facile, le V10 atmosph\u00e9rique de 610cv combmera toutes vos envies de performances. Sinon, la Ferrari F8 Spider pourrait \u00e9galement vous convenir!<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-37080\" src=\"https:\/\/car4rent.fr\/wp-content\/uploads\/IMG_2013-scaled-2.jpg\" alt=\"Location de voiture exotique, location de voitures de luxe \u00e0 cannes, Abonnement voiture de luxe, essai de lamborghini, Location de voiture Nice a\u00e9roport, Louer une voiture de sport Nice a\u00e9roport, Louer une voiture de sport \u00e0 Cannes, Louer une d\u00e9capotable, Louer une voiture sportive, Cannes location de voiture de luxe, Location de voiture de sport sur la C\u00f4te d&#039;azur, Location de voiture de luxe\" width=\"277\" height=\"208\" title=\"Car4Rent Cannes\" srcset=\"https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2.jpg 2304w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-300x225.jpg 300w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-1030x773.jpg 1030w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-768x576.jpg 768w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-1536x1152.jpg 1536w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-2048x1536.jpg 2048w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-1500x1125.jpg 1500w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-705x529.jpg 705w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/IMG_2013-scaled-2-450x338.jpg 450w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/><img decoding=\"async\" class=\"alignnone wp-image-37064 \" src=\"https:\/\/car4rent.fr\/wp-content\/uploads\/about-Car4rent-2-1-scaled-2.jpg\" alt=\"Location de voiture exotique, location de voitures de luxe \u00e0 cannes, location de voitures de sport nice a\u00e9roport, Location de voiture de sport Nice A\u00e9roport, Louer une voiture de sport \u00e0 cannes, location de voiture de prestige \u00e0 Monaco, Location de voiture de luxe \u00e0 Cannes, Louer une voiture de luxe sur la C\u00f4te d&#039;Azur,location de voitures de luxe Monaco, Location d&#039;une voiture de sport sur la cote d&#039;azur, Location de voiture de luxe \u00e0 Monaco, Location de voiture de luxe, Location de voiture de luxe pas cher\" width=\"277\" height=\"208\" title=\"Car4Rent Cannes\" srcset=\"https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2.jpg 2304w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-300x225.jpg 300w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-1030x773.jpg 1030w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-768x576.jpg 768w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-1536x1152.jpg 1536w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-2048x1536.jpg 2048w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-1500x1125.jpg 1500w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-705x529.jpg 705w, https:\/\/car4rent.fr\/wp-content\/uploads\/\/about-Car4rent-2-1-scaled-2-450x338.jpg 450w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/><\/p>\n<p>Les affaires et le plaisir se m\u00e9langent sur la C\u00f4te d&rsquo;Azur, de la meilleure fa\u00e7on possible et dans un environnement joyeux qui fait que tout s&rsquo;y passe bien. Et ne vous laissez pas surprendre par cette forme unique d&rsquo;h\u00e9donisme raffin\u00e9 qui s&rsquo;impose comme un mode de vie que vous serez heureux d&rsquo;adopter. En effet, \u00e0 Cannes, il est facile de trouver de tout : des bo\u00eetes de nuit branch\u00e9es, des boutiques de marque, des casinos chics, des h\u00f4tels cinq \u00e9toiles avec des services haut de gamme.<\/p>\n<p>Dans les rues de la ville, vous verrez tr\u00e8s probablement des dizaines de marques de v\u00e9hicules de luxe qu&rsquo;il est tr\u00e8s facile de louer pour compl\u00e9ter votre exp\u00e9rience globale. Cannes est rest\u00e9 l&rsquo;un des lieux authentiques de la plan\u00e8te, o\u00f9 l&rsquo;on a le plus de chances de croiser toutes sortes de voitures de luxe. C&rsquo;est comme une semaine de la mode automobile, sauf qu&rsquo;elle dure plus d&rsquo;une semaine !<\/p>\n<h3><strong>Location de voiture exotique et prise en charge \u00e0 l&rsquo;a\u00e9roport de Nice<\/strong><\/h3>\n<p>Votre voiture pourra vous \u00eatre livr\u00e9e directement \u00e0 l&rsquo;<a href=\"https:\/\/www.nice.aeroport.fr\/\" target=\"_blank\" rel=\"noopener\">a\u00e9roport international C\u00f4te d&rsquo;Azur de Nice,<\/a> ou \u00e0 n&rsquo;importe quelle autre destination en France et sur demande:\u00e0 votre domicile, votre h\u00f4tel, votre bureau ou sur votre lieu de vill\u00e9giature<\/p>\n<h3><strong>La location de voiture exotique avec un service client de premier ordre<\/strong><\/h3>\n<p>R\u00e9servez une location de voiture \u00e0 Cannes avec Car4rent. Notre \u00e9quipe sera attentive \u00e0 vos demandes et se mettra en quatre pour faire de votre exp\u00e9rience de conduite une exp\u00e9rience sensationnelle. Elle sera \u00e0 votre disposition pour veiller \u00e0 ce que chaque d\u00e9tail soit r\u00e9gl\u00e9 pour faire de votre voyage un moment inoubliable. Notre service ne s&rsquo;arr\u00eate pas \u00e0 la livraison du v\u00e9hicule. Si vous rencontrez un probl\u00e8me pendant votre s\u00e9jour, n&rsquo;h\u00e9sitez pas \u00e0 nous en faire part et nous essaierons d&rsquo;y trouver avec vous une solution.<\/p>\n<p>Vous souhaitez louer une voiture de luxe, n&rsquo;h\u00e9sitez pas \u00e0 <a href=\"https:\/\/car4rent.fr\/fr\/contact\/\" target=\"_blank\" rel=\"noopener\">contacter <\/a>notre \u00e9quipe pour toute information compl\u00e9mentaire.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"block1\" class=\"stripe row-content block1 fullwidth\">\n<\/section>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-86za2ja-a11e91e75e6f5a138e0e924ba6f5559e\">\n.flex_column.av-86za2ja-a11e91e75e6f5a138e0e924ba6f5559e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-86za2ja-a11e91e75e6f5a138e0e924ba6f5559e av_one_third  avia-builder-el-7  el_after_av_textblock  el_before_av_one_third  first flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7sbll2u-05d7a43dd65f21e7554db949836b1e38\">\n.iconbox.av-7sbll2u-05d7a43dd65f21e7554db949836b1e38 .iconbox_icon{\nbackground-color:#6834bd;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-7sbll2u-05d7a43dd65f21e7554db949836b1e38  avia-builder-el-8  avia-builder-el-no-sibling  main_color' ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue82a' data-av_iconfont='entypo-fontello'  ><\/div><\/header><div class='iconbox_content_container ' ><p><span style=\"font-size: 14pt;\">Location de voiture luxe<\/span><\/p>\n<hr \/>\n<p>Nous proposons \u00e0 la location des voitures de luxe et de sport, mais \u00e9galement une large gamme de SUV et de cabriolets. D\u00e9couvrez nos voitures de r\u00eave.<\/p>\n<p>Prix \u00e0 partir de 260\u20ac \/ jour.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-75vqic6-4ed136b987fd13aef95bb58e909fb9ee\">\n.flex_column.av-75vqic6-4ed136b987fd13aef95bb58e909fb9ee{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-75vqic6-4ed136b987fd13aef95bb58e909fb9ee av_one_third  avia-builder-el-9  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6hfj9li-3276b53c90d520a5355f7085810cfa99\">\n.iconbox.av-6hfj9li-3276b53c90d520a5355f7085810cfa99 .iconbox_icon{\nbackground-color:#6834bd;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-6hfj9li-3276b53c90d520a5355f7085810cfa99  avia-builder-el-10  avia-builder-el-no-sibling  main_color' ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue842' data-av_iconfont='entypo-fontello'  ><\/div><\/header><div class='iconbox_content_container ' ><p><span style=\"font-size: 14pt;\">Agences \u00e0 l\u2019a\u00e9roport de Nice, Cannes, Monaco et Saint-Tropez<\/span><\/p>\n<hr \/>\n<p>Nous livrons votre voiture o\u00f9 vous le souhaitez, \u00e0 votre arriv\u00e9e \u00e0 l&rsquo;a\u00e9roport de Nice, votre h\u00f4tel, votre lieu de vill\u00e9giature ou sur demande n&rsquo;importe o\u00f9 en France.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6ebucie-c56b2473464dd1a2ff5e19e5bfebc48a\">\n.flex_column.av-6ebucie-c56b2473464dd1a2ff5e19e5bfebc48a{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-6ebucie-c56b2473464dd1a2ff5e19e5bfebc48a av_one_third  avia-builder-el-11  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5p55bcm-431ab070185e0b865fe951f4d6ac00fe\">\n.iconbox.av-5p55bcm-431ab070185e0b865fe951f4d6ac00fe .iconbox_icon{\nbackground-color:#6834bd;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-5p55bcm-431ab070185e0b865fe951f4d6ac00fe  avia-builder-el-12  avia-builder-el-no-sibling  main_color' ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Ic\u00f4ne : \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue80b' data-av_iconfont='entypo-fontello'  ><\/div><\/header><div class='iconbox_content_container ' ><p><span style=\"font-size: 14pt;\">Un service sur mesure<\/span><\/p>\n<hr \/>\n<p>Une \u00e9quipe d\u00e9vou\u00e9e et attentive se tient \u00e0 votre disposition pour vous fournir toute information ou r\u00e9pondre \u00e0 vos demandes.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='contactez-nous'  class='avia-section av-54t0kra-7d406aa7871741b1cfbc2e5993d3c23e main_color avia-section-default avia-no-border-styling  avia-builder-el-13  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30641'><div class='entry-content-wrapper clearfix'>\n<div  class='hr av-4vxcy2e-9e711fd010b8a60bba291341fa5fc249 hr-default  avia-builder-el-14  el_before_av_heading  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4kz5ufq-d8312dc3c307d4986553424183bad880\">\n#top .av-special-heading.av-4kz5ufq-d8312dc3c307d4986553424183bad880{\npadding-bottom:25px;\n}\nbody .av-special-heading.av-4kz5ufq-d8312dc3c307d4986553424183bad880 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-4kz5ufq-d8312dc3c307d4986553424183bad880 .av-subheading{\nfont-size:20px;\n}\n<\/style>\n<div  class='av-special-heading av-4kz5ufq-d8312dc3c307d4986553424183bad880 av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-15  el_after_av_hr  el_before_av_hr '><h3 class='av-special-heading-tag '  >Vous souhaitez louer une voiture exotique sur la C\u00f4te d\u2019Azur ? Besoin d\u2019un conseil ?<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4274512-2ddd0f6ddd1f606b4814b92d1619fa12\">\n#top .hr.hr-invisible.av-4274512-2ddd0f6ddd1f606b4814b92d1619fa12{\nheight:25px;\n}\n<\/style>\n<div  class='hr av-4274512-2ddd0f6ddd1f606b4814b92d1619fa12 hr-invisible  avia-builder-el-16  el_after_av_heading  el_before_av_two_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3aogzkm-ca056d41cbc7937176a4194ae19f4b92\">\n.flex_column.av-3aogzkm-ca056d41cbc7937176a4194ae19f4b92{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3aogzkm-ca056d41cbc7937176a4194ae19f4b92 av_two_third  avia-builder-el-17  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><p><section  class='av_textblock_section av-3q9iae-d46de1c8f152197bc764ab38fff8bc83 '  ><div class='avia_textblock' ><p><span style=\"font-size: 14pt;\">Contactez-nous \u00e0 l\u2019aide du formulaire ci-dessous<\/span><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-2fpij06-0813267da3876c5da002bdf518af824c '  ><div class='avia_textblock' ><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-27233\"><form id=\"wpforms-form-27233\" class=\"wpforms-validate wpforms-form\" data-formid=\"27233\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/30641\" data-token=\"ea956caa849f38ed111b97e9a0a1fee9\" data-token-time=\"1784092258\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27233-field_5-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"5\"><label class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-27233-field_5\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][5][first]\" required><label for=\"wpforms-27233-field_5\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-27233-field_5-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][5][last]\" required><label for=\"wpforms-27233-field_5-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-27233-field_9-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"9\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-27233-field_7-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-27233-field_7\">Courriel <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-27233-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" spellcheck=\"false\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-27233-field_8-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-27233-field_8\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-27233-field_8\" class=\"wpforms-field-medium wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][8]\" aria-label=\"T\u00e9l\u00e9phone\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-27233-field_4-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-27233-field_4\">Message<\/label><textarea id=\"wpforms-27233-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27233\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages\/30641\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27233\" class=\"wpforms-submit\" data-alt-text=\"Envoi\" data-submit-text=\"Soumettre\" aria-live=\"assertive\" value=\"wpforms-submit\">Soumettre<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-25of4ly-d5d1d295b2bb1b31fe4564314bd544cb\">\n.flex_column.av-25of4ly-d5d1d295b2bb1b31fe4564314bd544cb{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-25of4ly-d5d1d295b2bb1b31fe4564314bd544cb av_one_third  avia-builder-el-20  el_after_av_two_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><p><section  class='av_textblock_section av-ltncuagj-3a48c2ea640cb1e6166548a03214881e '  ><div class='avia_textblock' ><p><span style=\"font-size: 14pt;\">Nous contacter par t\u00e9l\u00e9phone<\/span><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-av_textblock-564067357eb74c20cdd60b282c9b50bd '  ><div class='avia_textblock' ><p>Agence de Cannes (09H-12H00 et 15H00-19H00)<br \/>\n10 rue Hibert, 06400 Cannes<br \/>\nT\u00e9l\u00e9phone : +<a href=\"tel:0033788278586\">33(0)7 88 27 85 86<\/a><br \/>\nMail : <a href=\"mailto:info@car4rent.fr\">info@car4rent.fr<\/a><\/p>\n<\/div><\/section><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-1cxnr86-c9d41a55a36dafb4fed0ffc3b9235409 main_color avia-section-default avia-no-border-styling  avia-builder-el-23  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-30641'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-builder-widget-area clearfix  avia-builder-el-24  avia-builder-el-no-sibling '><div id=\"text-9\" class=\"widget clearfix widget_text\">\t\t\t<div class=\"textwidget\"><p style=\"text-align: center;\">    <div class=\"car4rent-share-block car4rent-fr\">\n        <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-facebook\"><\/i> Partager<\/a>\n        <a href=\"https:\/\/x.com\/intent\/tweet?url=&amp;text=\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-x-twitter\"><\/i> X<\/a>\n        <a href=\"https:\/\/wa.me\/?text=%20\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-whatsapp\"><\/i> WhatsApp<\/a>\n        <a href=\"https:\/\/www.instagram.com\/car4rent_cannes\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-instagram\"><\/i> Instagram<\/a>\n        <a href=\"https:\/\/www.linkedin.com\/company\/car4rent\/about\/\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-linkedin\"><\/i> LinkedIn<\/a>\n        <a href=\"https:\/\/www.youtube.com\/@car4rentcannes839\" target=\"_blank\" rel=\"noopener\"><i class=\"fa-brands fa-youtube\"><\/i> YouTube<\/a>\n    <\/div>\n    <\/p>\n<\/div>\n\t\t<\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":29526,"parent":0,"menu_order":720,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30641","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages\/30641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/comments?post=30641"}],"version-history":[{"count":0,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/pages\/30641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/media\/29526"}],"wp:attachment":[{"href":"https:\/\/car4rent.fr\/fr\/wp-json\/wp\/v2\/media?parent=30641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}